{"id":18,"count":6,"description":"","link":"https:\/\/exigotech.co\/au\/blog\/category\/telstra","name":"Telstra","slug":"telstra","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/exigotech.co\/in\/wp-json\/wp\/v2\/categories\/18","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exigotech.co\/in\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/exigotech.co\/in\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/exigotech.co\/in\/wp-json\/wp\/v2\/posts?categories=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}